{"id":17816,"date":"2025-07-14T15:21:42","date_gmt":"2025-07-14T13:21:42","guid":{"rendered":"https:\/\/www.gestingral.com\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/"},"modified":"2025-07-14T15:21:42","modified_gmt":"2025-07-14T13:21:42","slug":"gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta","status":"publish","type":"post","link":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/","title":{"rendered":"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta?"},"content":{"rendered":"<p>Parece mentira, pero de aqu\u00ed a una semana empieza una nueva campa\u00f1a de la Renta \u2013\u00a1c\u00f3mo pasa el tiempo!- y como cada a\u00f1o muchos ciudadanos tienen dudas sobre si tienen que hacer o no la declaraci\u00f3n. Pues bien, aqu\u00ed ten\u00e9is la respuesta.<\/p>\n<p>Por regla general, todas aquellas personas que hayan cobrado m\u00e1s de 22.000 euros brutos en el 2016 est\u00e1n obligados a hacer la declaraci\u00f3n de la Renta. Tambi\u00e9n deben hacerlo obligatoriamente todas las personas que hayan trabajado en dos o m\u00e1s puestos en el transcurso del a\u00f1o y hayan ganado m\u00e1s de 12.000 euros, siempre que en el segundo y el resto de puestos (excepto el principal) se haya ingresado m\u00e1s de 1.500 euros entre todos ellos. <\/p>\n<p>Adem\u00e1s, si ha vendido un piso, un parking o cualquier otro inmueble durante el a\u00f1o pasado o bien si ha ganado m\u00e1s de 1.600 euros en intereses o dividendos, tambi\u00e9n debe hacer la declaraci\u00f3n aunque no llegue a los l\u00edmites de ingresos que especific\u00e1bamos en el anterior p\u00e1rrafo. Y es que como ocurre en casi todo en la vida, siempre hay excepciones a la regla general. <\/p>\n<p><strong>Art\u00edculo quincenal de la Renta2016<\/strong><\/p>\n<p>A partir de hoy, Gestingral publicar\u00e1 un art\u00edculo quincenal en este diario informando y resolviendo dudas sobre la campa\u00f1a de la Renta de este a\u00f1o, que arranca oficialmente el 5 de abril. As\u00ed, ya estamos dando horas de visita con todo el mundo que lo solicite para que pueda venir a hacer ya la declaraci\u00f3n y cobrar la devoluci\u00f3n cuanto antes (#RendaGestingral). <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parece mentira, pero de aqu\u00ed a una semana empieza una nueva campa\u00f1a de la Renta  [&#8230;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[508,473],"tags":[1331,1134,566,1333],"class_list":["post-17816","post","type-post","status-publish","format-standard","hentry","category-autonomos-es","category-particulares-es","tag-rendagestingral-es","tag-declaracion-de-la-renta-es-2","tag-renda-es","tag-sueldo-bruto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta? &#8226; Serveis d&#039;assessoria i gestoria.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta? &#8226; Serveis d&#039;assessoria i gestoria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/\" \/>\n<meta property=\"og:site_name\" content=\"Gestingral Assessoria a Vilanova i la Geltr\u00fa.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Gestingral\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-14T13:21:42+00:00\" \/>\n<meta name=\"author\" content=\"Sergi Pujol Lopez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gestingral\" \/>\n<meta name=\"twitter:site\" content=\"@gestingral\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergi Pujol Lopez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\\\/\"},\"author\":{\"name\":\"Sergi Pujol Lopez\",\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/#\\\/schema\\\/person\\\/692b3d91aafe1f593dca3f67838304c1\"},\"headline\":\"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta?\",\"datePublished\":\"2025-07-14T13:21:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\\\/\"},\"wordCount\":286,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/#organization\"},\"keywords\":[\"#RendaGestingral\",\"declaraci\u00f3n de la Renta\",\"Renda\",\"sueldo bruto\"],\"articleSection\":[\"Aut\u00f3nomos\",\"Particulares\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.gestingral.com\\\/es\\\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\\\/\",\"url\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\\\/\",\"name\":\"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta? &#8226; Serveis d'assessoria i gestoria.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/#website\"},\"datePublished\":\"2025-07-14T13:21:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gestingral.com\\\/es\\\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/\",\"name\":\"Gestingral Assessoria a Vilanova i la Geltr\u00fa.\",\"description\":\"Assessors - Consultors - Advocats\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/#organization\",\"name\":\"Gestingral Assessoria\",\"url\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gestingral.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/gestingral-logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/www.gestingral.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/gestingral-logo-retina.png\",\"width\":340,\"height\":342,\"caption\":\"Gestingral Assessoria\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Gestingral\",\"https:\\\/\\\/x.com\\\/gestingral\",\"https:\\\/\\\/www.instagram.com\\\/gestingral\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gestingral\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/#\\\/schema\\\/person\\\/692b3d91aafe1f593dca3f67838304c1\",\"name\":\"Sergi Pujol Lopez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e392f65d731d0f3356f4bd58b49881bb72aa3cd28fd7183113b372ab06cccb0b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e392f65d731d0f3356f4bd58b49881bb72aa3cd28fd7183113b372ab06cccb0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e392f65d731d0f3356f4bd58b49881bb72aa3cd28fd7183113b372ab06cccb0b?s=96&d=mm&r=g\",\"caption\":\"Sergi Pujol Lopez\"},\"url\":\"https:\\\/\\\/www.gestingral.com\\\/es\\\/author\\\/spujol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta? &#8226; Serveis d'assessoria i gestoria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/","og_locale":"es_ES","og_type":"article","og_title":"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta? &#8226; Serveis d'assessoria i gestoria.","og_url":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/","og_site_name":"Gestingral Assessoria a Vilanova i la Geltr\u00fa.","article_publisher":"https:\/\/www.facebook.com\/Gestingral","article_published_time":"2025-07-14T13:21:42+00:00","author":"Sergi Pujol Lopez","twitter_card":"summary_large_image","twitter_creator":"@gestingral","twitter_site":"@gestingral","twitter_misc":{"Escrito por":"Sergi Pujol Lopez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/#article","isPartOf":{"@id":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/"},"author":{"name":"Sergi Pujol Lopez","@id":"https:\/\/www.gestingral.com\/es\/#\/schema\/person\/692b3d91aafe1f593dca3f67838304c1"},"headline":"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta?","datePublished":"2025-07-14T13:21:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/"},"wordCount":286,"commentCount":0,"publisher":{"@id":"https:\/\/www.gestingral.com\/es\/#organization"},"keywords":["#RendaGestingral","declaraci\u00f3n de la Renta","Renda","sueldo bruto"],"articleSection":["Aut\u00f3nomos","Particulares"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/","url":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/","name":"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta? &#8226; Serveis d'assessoria i gestoria.","isPartOf":{"@id":"https:\/\/www.gestingral.com\/es\/#website"},"datePublished":"2025-07-14T13:21:42+00:00","breadcrumb":{"@id":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gestingral.com\/es\/gestingral-te-informa-quien-debe-hacer-la-declaracion-de-la-renta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.gestingral.com\/es\/"},{"@type":"ListItem","position":2,"name":"Gestingral te informa: \u00bfQui\u00e9n debe hacer la declaraci\u00f3n de la Renta?"}]},{"@type":"WebSite","@id":"https:\/\/www.gestingral.com\/es\/#website","url":"https:\/\/www.gestingral.com\/es\/","name":"Gestingral Assessoria a Vilanova i la Geltr\u00fa.","description":"Assessors - Consultors - Advocats","publisher":{"@id":"https:\/\/www.gestingral.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gestingral.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.gestingral.com\/es\/#organization","name":"Gestingral Assessoria","url":"https:\/\/www.gestingral.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gestingral.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.gestingral.com\/wp-content\/uploads\/2021\/03\/gestingral-logo-retina.png","contentUrl":"https:\/\/www.gestingral.com\/wp-content\/uploads\/2021\/03\/gestingral-logo-retina.png","width":340,"height":342,"caption":"Gestingral Assessoria"},"image":{"@id":"https:\/\/www.gestingral.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Gestingral","https:\/\/x.com\/gestingral","https:\/\/www.instagram.com\/gestingral","https:\/\/www.linkedin.com\/company\/gestingral"]},{"@type":"Person","@id":"https:\/\/www.gestingral.com\/es\/#\/schema\/person\/692b3d91aafe1f593dca3f67838304c1","name":"Sergi Pujol Lopez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e392f65d731d0f3356f4bd58b49881bb72aa3cd28fd7183113b372ab06cccb0b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e392f65d731d0f3356f4bd58b49881bb72aa3cd28fd7183113b372ab06cccb0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e392f65d731d0f3356f4bd58b49881bb72aa3cd28fd7183113b372ab06cccb0b?s=96&d=mm&r=g","caption":"Sergi Pujol Lopez"},"url":"https:\/\/www.gestingral.com\/es\/author\/spujol\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gestingral.com\/es\/wp-json\/wp\/v2\/posts\/17816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gestingral.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gestingral.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gestingral.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gestingral.com\/es\/wp-json\/wp\/v2\/comments?post=17816"}],"version-history":[{"count":0,"href":"https:\/\/www.gestingral.com\/es\/wp-json\/wp\/v2\/posts\/17816\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.gestingral.com\/es\/wp-json\/wp\/v2\/media?parent=17816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gestingral.com\/es\/wp-json\/wp\/v2\/categories?post=17816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gestingral.com\/es\/wp-json\/wp\/v2\/tags?post=17816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}